{"id":4819,"date":"2021-08-11T09:00:00","date_gmt":"2021-08-11T13:00:00","guid":{"rendered":"https:\/\/blog.source.immo\/?p=183"},"modified":"2023-01-06T06:58:31","modified_gmt":"2023-01-06T11:58:31","slug":"4-risques-a-surveiller-dans-votre-demeure","status":"publish","type":"post","link":"https:\/\/dorisdimitri.com\/en\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/","title":{"rendered":"4 risques \u00e0 surveiller dans votre demeure"},"content":{"rendered":"\n<p><strong>Partout o\u00f9 l\u2019on va, il y a des risques. M\u00eame dans votre maison, vous pouvez vous blesser en tr\u00e9buchant, par exemple. Certains risques sont cependant plus insidieux\u00a0: si on ne fait pas attention ou si on les laisse s\u2019aggraver, ils peuvent causer du tort \u00e0 votre sant\u00e9 ou \u00e0 votre maison.<\/strong><\/p>\n\n\n\n<p>Voici quatre risques qu\u2019il ne faut pas n\u00e9gliger et la fa\u00e7on dont on peut s\u2019en prot\u00e9ger.<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li><strong>L\u2019humidit\u00e9<\/strong><\/li><\/ol>\n\n\n\n<p>Un peu d\u2019humidit\u00e9, c\u2019est bien, mais trop, c\u2019est\u2026 trop ! Si le taux d\u2019humidit\u00e9 \u00e0 l\u2019int\u00e9rieur de votre demeure d\u00e9passe constamment 70&nbsp;%, votre maison peut en souffrir. Vous aussi pouvez en subir les cons\u00e9quences, sous forme de probl\u00e8mes respiratoires ou d\u2019irritations.<\/p>\n\n\n\n<p>Trop d\u2019humidit\u00e9 dans l\u2019air peut notamment endommager la charpente de bois de la maison, d\u00e9coller la peinture et favoriser l\u2019apparition de moisissures.<\/p>\n\n\n\n<p>Si vous avez l\u2019impression de vivre dans un sous-sol humide, ou qu\u2019un appareil vous indique que l\u2019humidit\u00e9 est trop grande, n\u2019attendez pas. Commencez par installer un d\u00e9shumidificateur. Mais si l\u2019air reste trop humide, consultez un sp\u00e9cialiste de la ventilation.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.centris.ca\/public\/cms\/qc\/consumersite\/acb0744bc3d74e41931741ad5963ed6c\/centris_risques_humidite_moisissure_2.jpg\" alt=\"\" \/><\/figure>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\"><li><strong>La moisissure<\/strong><\/li><\/ol>\n\n\n\n<p>La pr\u00e9sence de moisissure dans une maison est un probl\u00e8me s\u00e9rieux qui peut nuire \u00e0 votre sant\u00e9 et \u00e0 celle de votre famille. Elle peut aggraver l\u2019asthme ou causer d\u2019autres probl\u00e8mes respiratoires ou r\u00e9actions allergiques.<\/p>\n\n\n\n<p>Si vous notez l\u2019apparition de moisissures, intervenez rapidement. Si les taches de moisissures sont encore petites et peu r\u00e9pandues, des produits vendus dans le commerce arriveront probablement \u00e0 en venir \u00e0 bout.<\/p>\n\n\n\n<p>Si le probl\u00e8me est plus s\u00e9rieux ou plus \u00e9tendu, par exemple si vous d\u00e9couvrez de la moisissure entre les murs, faites appel \u00e0 des sp\u00e9cialistes du nettoyage des sinistres. Retirer la moisissure est une op\u00e9ration d\u00e9licate, parce qu\u2019il faut \u00e9viter d\u2019y \u00eatre expos\u00e9 et de les r\u00e9pandre partout dans la maison. Il est probable que vous ayez aussi \u00e0 remplacer des sections de murs atteints par la moisissure.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"3\"><li><strong>Le plomb<\/strong><\/li><\/ol>\n\n\n\n<p>Anciennement, les tuyaux de la plomberie ou de la canalisation \u00e9taient souvent en plomb. Avec le temps, ce plomb se retrouve dans l\u2019eau du robinet. Si votre maison a un certain \u00e2ge ou si vous soup\u00e7onnez que les tuyaux sont en plomb, faites analyser l\u2019eau.<\/p>\n\n\n\n<p>Le plomb est n\u00e9faste \u00e0 long terme pour la sant\u00e9. Il peut avoir un effet dommageable sur le d\u00e9veloppement des enfants qui y sont expos\u00e9s.<\/p>\n\n\n\n<p>M\u00eame si l\u2019exposition au plomb est plus rare qu\u2019autrefois, le probl\u00e8me touche encore plusieurs r\u00e9sidences et secteurs. Montr\u00e9al a effectu\u00e9 des tests r\u00e9cemment pour mesurer la pr\u00e9sence de plomb dans plusieurs secteurs, afin de r\u00e9nover les canalisations d\u00e9ficientes.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn.centris.ca\/public\/cms\/qc\/consumersite\/acb0744bc3d74e41931741ad5963ed6c\/centris_risques_humidite_moisissure_3.jpg\" alt=\"\" \/><\/figure>\n\n\n\n<ol class=\"wp-block-list\" start=\"4\"><li><strong>Le radon<\/strong><\/li><\/ol>\n\n\n\n<p>Il suffit de dire que le radon est un gaz radioactif pour comprendre qu\u2019il peut avoir un effet n\u00e9faste sur la sant\u00e9.<\/p>\n\n\n\n<p>\u00c0 l\u2019\u00e9tat naturel, ce produit de la d\u00e9composition de l\u2019uranium se disperse rapidement dans l\u2019air et ne pose pas de danger pour la sant\u00e9. Il y en a dans toutes les maisons.<\/p>\n\n\n\n<p>Le radon s\u2019infiltre dans la maison par des fissures ou des joints. Quand il se trouve enferm\u00e9 dans un espace clos comme une maison, il se peut que cela m\u00e8ne \u00e0 une concentration trop forte qui peut entra\u00eener un risque pour la sant\u00e9, notamment sous forme de cancer du poumon. Il est pr\u00e9f\u00e9rable d\u2019effectuer un test de radon pour v\u00e9rifier sa concentration.<\/p>\n\n\n\n<p>En cas de probl\u00e8me, vous n\u2019avez pas le choix\u00a0: il faut consulter un sp\u00e9cialiste en r\u00e9duction de la pr\u00e9sence de radon dans les maisons.<\/p>\n\n\n\n<p><em>Source : blogue de Centris : <a href=\"https:\/\/www.centris.ca\/fr\/blogue\/astuces-et-deco\/4-risques-a-surveiller-dans-votre-demeure?uc=0\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.centris.ca\/fr\/blogue\/astuces-et-deco\/4-risques-a-surveiller-dans-votre-demeure?uc=0<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Partout o\u00f9 l\u2019on va, il y a des risques. M\u00eame dans votre maison, vous pouvez vous blesser en tr\u00e9buchant, par exemple. Certains risques sont cependant plus insidieux\u00a0: si on ne fait pas attention ou si on les laisse s\u2019aggraver, ils peuvent causer du tort \u00e0 votre sant\u00e9 ou \u00e0 votre maison.<\/p>\n","protected":false},"author":1,"featured_media":5269,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,14],"tags":[],"class_list":["post-4819","post","type-post","status-publish","format-standard","hentry","category-aliquando","category-entretien"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>4 risques \u00e0 surveiller dans votre demeure - Doris Dimitri<\/title>\n<meta name=\"description\" content=\"Partout o\u00f9 l\u2019on va, il y a des risques. M\u00eame dans votre maison, vous pouvez vous blesser en tr\u00e9buchant, par exemple. Certains risques sont cependant plus insidieux\u00a0: si on ne fait pas attention ou si on les laisse s\u2019aggraver, ils peuvent causer du tort \u00e0 votre sant\u00e9 ou \u00e0 votre maison.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 risques \u00e0 surveiller dans votre demeure\" \/>\n<meta property=\"og:description\" content=\"Partout o\u00f9 l\u2019on va, il y a des risques. M\u00eame dans votre maison, vous pouvez vous blesser en tr\u00e9buchant, par exemple. Certains risques sont cependant plus insidieux\u00a0: si on ne fait pas attention ou si on les laisse s\u2019aggraver, ils peuvent causer du tort \u00e0 votre sant\u00e9 ou \u00e0 votre maison.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/\" \/>\n<meta property=\"og:site_name\" content=\"Doris Dimitri\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DorisDimitriCourtier\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-11T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-06T11:58:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/09\/risques-humidite-moisissure.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"4 risques \u00e0 surveiller dans votre demeure\" \/>\n<meta name=\"twitter:description\" content=\"Partout o\u00f9 l\u2019on va, il y a des risques. M\u00eame dans votre maison, vous pouvez vous blesser en tr\u00e9buchant, par exemple. Certains risques sont cependant plus insidieux\u00a0: si on ne fait pas attention ou si on les laisse s\u2019aggraver, ils peuvent causer du tort \u00e0 votre sant\u00e9 ou \u00e0 votre maison.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/09\/risques-humidite-moisissure.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"4 risques \u00e0 surveiller dans votre demeure\",\"datePublished\":\"2021-08-11T13:00:00+00:00\",\"dateModified\":\"2023-01-06T11:58:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/\"},\"wordCount\":647,\"image\":{\"@id\":\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/09\/risques-humidite-moisissure.jpg\",\"articleSection\":[\"Aliquando\",\"Entretien\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/\",\"url\":\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/\",\"name\":\"4 risques \u00e0 surveiller dans votre demeure - Doris Dimitri\",\"isPartOf\":{\"@id\":\"https:\/\/dorisdimitri.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/09\/risques-humidite-moisissure.jpg\",\"datePublished\":\"2021-08-11T13:00:00+00:00\",\"dateModified\":\"2023-01-06T11:58:31+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Partout o\u00f9 l\u2019on va, il y a des risques. M\u00eame dans votre maison, vous pouvez vous blesser en tr\u00e9buchant, par exemple. Certains risques sont cependant plus insidieux\u00a0: si on ne fait pas attention ou si on les laisse s\u2019aggraver, ils peuvent causer du tort \u00e0 votre sant\u00e9 ou \u00e0 votre maison.\",\"breadcrumb\":{\"@id\":\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#primaryimage\",\"url\":\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/09\/risques-humidite-moisissure.jpg\",\"contentUrl\":\"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/09\/risques-humidite-moisissure.jpg\",\"width\":700,\"height\":467},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dorisdimitri.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4 risques \u00e0 surveiller dans votre demeure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dorisdimitri.com\/#website\",\"url\":\"https:\/\/dorisdimitri.com\/\",\"name\":\"Doris Dimitri\",\"description\":\"Courtier immobilier\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dorisdimitri.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/dorisdimitri.com\/en\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 risques \u00e0 surveiller dans votre demeure - Doris Dimitri","description":"Partout o\u00f9 l\u2019on va, il y a des risques. M\u00eame dans votre maison, vous pouvez vous blesser en tr\u00e9buchant, par exemple. Certains risques sont cependant plus insidieux\u00a0: si on ne fait pas attention ou si on les laisse s\u2019aggraver, ils peuvent causer du tort \u00e0 votre sant\u00e9 ou \u00e0 votre maison.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/","og_locale":"en_US","og_type":"article","og_title":"4 risques \u00e0 surveiller dans votre demeure","og_description":"Partout o\u00f9 l\u2019on va, il y a des risques. M\u00eame dans votre maison, vous pouvez vous blesser en tr\u00e9buchant, par exemple. Certains risques sont cependant plus insidieux\u00a0: si on ne fait pas attention ou si on les laisse s\u2019aggraver, ils peuvent causer du tort \u00e0 votre sant\u00e9 ou \u00e0 votre maison.","og_url":"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/","og_site_name":"Doris Dimitri","article_publisher":"https:\/\/www.facebook.com\/DorisDimitriCourtier\/","article_published_time":"2021-08-11T13:00:00+00:00","article_modified_time":"2023-01-06T11:58:31+00:00","og_image":[{"url":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/09\/risques-humidite-moisissure.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"4 risques \u00e0 surveiller dans votre demeure","twitter_description":"Partout o\u00f9 l\u2019on va, il y a des risques. M\u00eame dans votre maison, vous pouvez vous blesser en tr\u00e9buchant, par exemple. Certains risques sont cependant plus insidieux\u00a0: si on ne fait pas attention ou si on les laisse s\u2019aggraver, ils peuvent causer du tort \u00e0 votre sant\u00e9 ou \u00e0 votre maison.","twitter_image":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/09\/risques-humidite-moisissure.jpg","twitter_misc":{"Written by":"","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#article","isPartOf":{"@id":"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/"},"author":{"name":"","@id":""},"headline":"4 risques \u00e0 surveiller dans votre demeure","datePublished":"2021-08-11T13:00:00+00:00","dateModified":"2023-01-06T11:58:31+00:00","mainEntityOfPage":{"@id":"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/"},"wordCount":647,"image":{"@id":"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/09\/risques-humidite-moisissure.jpg","articleSection":["Aliquando","Entretien"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/","url":"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/","name":"4 risques \u00e0 surveiller dans votre demeure - Doris Dimitri","isPartOf":{"@id":"https:\/\/dorisdimitri.com\/#website"},"primaryImageOfPage":{"@id":"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#primaryimage"},"image":{"@id":"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/09\/risques-humidite-moisissure.jpg","datePublished":"2021-08-11T13:00:00+00:00","dateModified":"2023-01-06T11:58:31+00:00","author":{"@id":""},"description":"Partout o\u00f9 l\u2019on va, il y a des risques. M\u00eame dans votre maison, vous pouvez vous blesser en tr\u00e9buchant, par exemple. Certains risques sont cependant plus insidieux\u00a0: si on ne fait pas attention ou si on les laisse s\u2019aggraver, ils peuvent causer du tort \u00e0 votre sant\u00e9 ou \u00e0 votre maison.","breadcrumb":{"@id":"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#primaryimage","url":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/09\/risques-humidite-moisissure.jpg","contentUrl":"https:\/\/blog.source.immo\/wp-content\/uploads\/2021\/09\/risques-humidite-moisissure.jpg","width":700,"height":467},{"@type":"BreadcrumbList","@id":"http:\/\/99612.b.aliquando.immo\/aliquando\/4-risques-a-surveiller-dans-votre-demeure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dorisdimitri.com\/"},{"@type":"ListItem","position":2,"name":"4 risques \u00e0 surveiller dans votre demeure"}]},{"@type":"WebSite","@id":"https:\/\/dorisdimitri.com\/#website","url":"https:\/\/dorisdimitri.com\/","name":"Doris Dimitri","description":"Courtier immobilier","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorisdimitri.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"","url":"https:\/\/dorisdimitri.com\/en\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/dorisdimitri.com\/en\/wp-json\/wp\/v2\/posts\/4819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorisdimitri.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorisdimitri.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorisdimitri.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorisdimitri.com\/en\/wp-json\/wp\/v2\/comments?post=4819"}],"version-history":[{"count":1,"href":"https:\/\/dorisdimitri.com\/en\/wp-json\/wp\/v2\/posts\/4819\/revisions"}],"predecessor-version":[{"id":4965,"href":"https:\/\/dorisdimitri.com\/en\/wp-json\/wp\/v2\/posts\/4819\/revisions\/4965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorisdimitri.com\/en\/wp-json\/wp\/v2\/media\/5269"}],"wp:attachment":[{"href":"https:\/\/dorisdimitri.com\/en\/wp-json\/wp\/v2\/media?parent=4819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorisdimitri.com\/en\/wp-json\/wp\/v2\/categories?post=4819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorisdimitri.com\/en\/wp-json\/wp\/v2\/tags?post=4819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}